{"id":340939,"date":"2020-01-01T13:47:00","date_gmt":"2020-01-01T12:47:00","guid":{"rendered":"https:\/\/hunterlab.de\/mesure-de-la-couleur-des-poudres-pharmaceutiques-2\/"},"modified":"2025-07-17T15:00:31","modified_gmt":"2025-07-17T14:00:31","slug":"mesure-de-la-couleur-des-poudres-pharmaceutiques","status":"publish","type":"post","link":"https:\/\/www.hunterlab.eu\/fr\/mesure-de-la-couleur-des-poudres-pharmaceutiques\/","title":{"rendered":"Mesure de la couleur des poudres pharmaceutiques"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_3_font=\u00a0\u00bb||||||||\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/hunterlab.de\/wp-content\/uploads\/2024\/04\/Agera-mit-Pulver-weiss-freisteller-DSCF9014-2880w-3-300x300.png\" width=\"300\" height=\"300\" alt=\"Agera-avec-poudre-blanche\" class=\"wp-image-284277 alignright size-medium\"><strong>Les poudres pharmaceutiques et les produits pharmaceutiques en vrac<\/strong> sont largement utilis\u00e9s pour d\u00e9velopper diff\u00e9rents types de m\u00e9dicaments, des g\u00e9lules <strong>et capsules de gel aux comprim\u00e9s<\/strong>. Ils subissent un processus de compression et sont \u00e9galement disponibles sous forme de poudre soluble. Que vous mesuriez le phosphate de cod\u00e9ine ou l&rsquo;hydrobromure d&rsquo;hyoscine, les plus grands fabricants de m\u00e9dicaments au monde font confiance aux solutions HunterLab pour garantir la <strong>qualit\u00e9 et la coh\u00e9rence<\/strong> des mati\u00e8res premi\u00e8res et des produits de consommation tout au long de la cha\u00eene de valeur.<\/p>\n<p>La couleur des <strong>poudres pharmaceutiques<\/strong> telles que le sorbitol, la cellulose microcristalline ou le phosphate de calcium dibasique anhydre est souvent mesur\u00e9e \u00e0 l&rsquo;arriv\u00e9e pour garantir <strong>la coh\u00e9rence des lots<\/strong>. La m\u00e9thode pr\u00e9f\u00e9r\u00e9e pour analyser les poudres est la mesure de la r\u00e9flexion. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_3_font=\u00a0\u00bb||||||||\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<img decoding=\"async\" src=\"https:\/\/hunterlab.de\/wp-content\/uploads\/2024\/04\/DSC00684AgeramitPulver-2880w-300x200.jpg\" width=\"300\" height=\"200\" alt=\"Agera+avec+poudre\" class=\"wp-image-284269 alignleft size-medium\"><strong>La mesure est expliqu\u00e9e de mani\u00e8re tr\u00e8s simple et compacte :<\/strong><\/p>\n<p>Tout d&rsquo;abord, on remplit une cuvette avec l&rsquo;\u00e9chantillon. On tape d\u00e9licatement la cuvette sur une surface dure pour que la poudre se d\u00e9pose un peu, puis on la place sur le diaphragme pour que la poudre puisse \u00eatre mesur\u00e9e \u00e0 travers le fond en verre de la cuvette. (Veillez \u00e0 ne pas mettre de poudre sur l&rsquo;ouverture du diaphragme).  <\/p>\n<p><strong>Il suffit d&rsquo;appuyer sur un bouton pour d\u00e9clencher la mesure de la couleur et afficher directement les valeurs mesur\u00e9es sur l&rsquo;\u00e9cran.<\/strong><\/p>\n<p><span style=\"color: #ff6600;\"><strong><a href=\"\/wp-content\/uploads\/2024\/04\/HLE-0005-Farbmessung-von-losem-Pulver.pdf\" target=\"_blank\" rel=\"noopener\" style=\"color: #E63D28;\">Lisez la m\u00e9thode de mesure d\u00e9taill\u00e9e ici.<\/a><\/strong><\/span>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.24.3&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_3_font=\u00a0\u00bb||||||||\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong><img decoding=\"async\" src=\"https:\/\/hunterlab.de\/wp-content\/uploads\/2024\/04\/Farbmessung-von-weissem-Pulver-HunterLab-Europe-1920w-300x192.jpg\" width=\"300\" height=\"192\" alt=\"Colorim\u00e9trie-de-la-poudre-blanche-HunterLab Europe\" class=\"wp-image-284285 alignright size-medium\"><br \/><\/strong>Quel que soit le type de <strong>poudre<\/strong> que vous souhaitez mesurer, les spectrophotom\u00e8tres HunterLab vous garantissent un <strong>aspect visuel constant<\/strong> et mettent en valeur vos normes de qualit\u00e9.<\/p>\n<p>[\/et_pb_text][difl_dual_button btn_left_background_bgcolor=\u00a0\u00bb#DC4A50&Prime; use_left_button_icon=\u00a0\u00bboff\u00a0\u00bb btn_right_background_bgcolor=\u00a0\u00bb#FFFFFF\u00a0\u00bb use_right_button_icon=\u00a0\u00bboff\u00a0\u00bb left_button=\u00a0\u00bbN&#039;h\u00e9sitez pas \u00e0 nous contacter, nous serons ravis de vous conseiller !\u00a0\u00bb left_button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjM4NTAiLCJlbmFibGVfaHRtbCI6Im9mZiJ9fQ==@\u00a0\u00bb left_button_wrapper_margin=\u00a0\u00bb|12px|||false|false\u00a0\u00bb right_button_wrapper_margin=\u00a0\u00bb|||12px|false|false\u00a0\u00bb left_button_padding=\u00a0\u00bb16px|24px|16px|24px|true|true\u00a0\u00bb left_button_padding_tablet=\u00a0\u00bb16px|24px|16px|24px|true|true\u00a0\u00bb left_button_padding_phone=\u00a0\u00bb16px|16px|16px|16px|true|true\u00a0\u00bb left_button_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb right_button_padding=\u00a0\u00bb16px|24px|16px|24px|true|true\u00a0\u00bb right_button_padding_tablet=\u00a0\u00bb16px|24px|16px|24px|true|true\u00a0\u00bb right_button_padding_phone=\u00a0\u00bb16px|16px|16px|16px|true|true\u00a0\u00bb right_button_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb alignment=\u00a0\u00bbleft\u00a0\u00bb alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb alignment_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.2&Prime; _dynamic_attributes=\u00a0\u00bbleft_button_url\u00a0\u00bb _module_preset=\u00a0\u00bbbe95d251-2d55-4926-b8b4-f039f8b01275&Prime; left_button_font=\u00a0\u00bb|700|||||||\u00a0\u00bb left_button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb left_button_font_size=\u00a0\u00bb16px\u00a0\u00bb left_button_line_height=\u00a0\u00bb22px\u00a0\u00bb right_button_font=\u00a0\u00bbNunito Sans|700|||||||\u00a0\u00bb right_button_text_color=\u00a0\u00bb#E63D28&Prime; right_button_font_size=\u00a0\u00bb16px\u00a0\u00bb right_button_line_height=\u00a0\u00bb22px\u00a0\u00bb custom_margin=\u00a0\u00bb20px||||false|false\u00a0\u00bb left_button_text_align_tablet=\u00a0\u00bb\u00a0\u00bb left_button_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb left_button_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb left_button_font_size_tablet=\u00a0\u00bb16px\u00a0\u00bb left_button_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb left_button_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb left_button_line_height_tablet=\u00a0\u00bb22px\u00a0\u00bb left_button_line_height_phone=\u00a0\u00bb20px\u00a0\u00bb left_button_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb right_button_font_size_tablet=\u00a0\u00bb16px\u00a0\u00bb right_button_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb right_button_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb right_button_line_height_tablet=\u00a0\u00bb22px\u00a0\u00bb right_button_line_height_phone=\u00a0\u00bb20px\u00a0\u00bb right_button_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_radii_left_button=\u00a0\u00bbon|4px|4px|4px|4px\u00a0\u00bb border_width_all_left_button=\u00a0\u00bb2px\u00a0\u00bb border_color_all_left_button=\u00a0\u00bb#DC4A50&Prime; border_radii_right_button=\u00a0\u00bbon|4px|4px|4px|4px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb btn_left_background_bgcolor__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb btn_left_background_bgcolor__hover=\u00a0\u00bb#FFFFFF\u00a0\u00bb left_button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb left_button_text_color__hover=\u00a0\u00bb#dc4a50&Prime; btn_right_background_bgcolor__hover_enabled=\u00a0\u00bbon|desktop\u00a0\u00bb btn_right_background_bgcolor__hover=\u00a0\u00bb#E63D28&Prime; right_button_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb right_button_text_color__hover=\u00a0\u00bb#FFFFFF\u00a0\u00bb][\/difl_dual_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les poudres pharmaceutiques et les produits pharmaceutiques en vrac sont largement utilis\u00e9s pour d\u00e9velopper diff\u00e9rents types de m\u00e9dicaments, des g\u00e9lules et capsules de gel aux comprim\u00e9s. Ils subissent un processus de compression et sont \u00e9galement disponibles sous forme de poudre soluble. Que vous mesuriez le phosphate de cod\u00e9ine ou l&rsquo;hydrobromure d&rsquo;hyoscine, les plus grands fabricants de m\u00e9dicaments au monde font confiance aux solutions HunterLab pour garantir la qualit\u00e9 et la coh\u00e9rence des mati\u00e8res premi\u00e8res et des produits de consommation tout au long de la cha\u00eene de valeur.<\/p>\n<p>La couleur des poudres pharmaceutiques telles que le sorbitol, la cellulose microcristalline ou le phosphate de calcium dibasique anhydre est souvent mesur\u00e9e \u00e0 l&rsquo;arriv\u00e9e pour garantir la coh\u00e9rence des lots. La m\u00e9thode pr\u00e9f\u00e9r\u00e9e pour analyser les poudres est la mesure de la r\u00e9flexion. <\/p>\n","protected":false},"author":2,"featured_media":284261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[808],"tags":[868,1897,1071],"class_list":["post-340939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colorimetrie","tag-colorimetrie","tag-poudre","tag-poudres-pharmaceutiques"],"_links":{"self":[{"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/posts\/340939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/comments?post=340939"}],"version-history":[{"count":0,"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/posts\/340939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/media\/284261"}],"wp:attachment":[{"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/media?parent=340939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/categories?post=340939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hunterlab.eu\/fr\/wp-json\/wp\/v2\/tags?post=340939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}